{"id":213,"date":"2021-12-02T16:57:24","date_gmt":"2021-12-02T15:57:24","guid":{"rendered":"https:\/\/technischemechanik.com\/?p=213"},"modified":"2021-12-05T14:50:34","modified_gmt":"2021-12-05T13:50:34","slug":"dynamik-kreisel-muhlstein","status":"publish","type":"post","link":"https:\/\/technischemechanik.com\/en\/2021\/12\/02\/dynamik-kreisel-muhlstein\/","title":{"rendered":"Kreiseldynamik: M\u00fchlstein"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Herzlich Willkommen!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heute wollen wir uns ein Beispiel aus dem Bereich Kreiseldynamik ansehen, und zwar folgende M\u00fchle:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Die dargestellte M\u00fchle wird mit der Winkelgeschwindigkeit&nbsp;\u03a9=const.&nbsp;angetrieben. Der M\u00fchlstein habe seinen Schwerpunkt in&nbsp;S, seine Masse sei&nbsp;m&nbsp;und seine Massentr\u00e4gheitsmomente&nbsp;I1&nbsp;sowie&nbsp;I2=I3.<\/p><p>Ges.:<br>*die erforderliche Winkelgeschwindigkeit&nbsp;\u03c9=const., sodass der M\u00fchlstein im Punkt&nbsp;P&nbsp;mit der Geschwindigkeit&nbsp;-vp e2&nbsp;gleitet.<br>*die Beschleunigung des Punktes&nbsp;P.<br>*die Winkelgeschwindigkeit des M\u00fchlsteins im&nbsp;e_1-e_2-e_3&nbsp;Koordinatensystem.<br>*die resultierende Einzelkraft und das resultierende Moment bei Reduktion in den Koordinatenursprung.<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"215\" data-permalink=\"https:\/\/technischemechanik.com\/en\/beispiel-r01\/\" data-orig-file=\"https:\/\/i0.wp.com\/technischemechanik.com\/wp-content\/uploads\/2021\/11\/beispiel-r01.jpg?fit=2732%2C2048&amp;ssl=1\" data-orig-size=\"2732,2048\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"beispiel-r01\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/technischemechanik.com\/wp-content\/uploads\/2021\/11\/beispiel-r01.jpg?fit=712%2C534&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/technischemechanik.com\/wp-content\/uploads\/2021\/11\/beispiel-r01.jpg?resize=712%2C533&#038;ssl=1\" alt=\"\" class=\"wp-image-215\" width=\"712\" height=\"533\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die Angabe gibt es als Download inkl. L\u00f6sungen um das Beispiel vorab rechnen zu k\u00f6nnen. <\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-826e46df-2ffa-4eb8-a599-964382345e79\" href=\"https:\/\/technischemechanik.com\/wp-content\/uploads\/2021\/12\/kreisel-k05-1.pdf\">Kreisel-K05<\/a><a href=\"https:\/\/technischemechanik.com\/wp-content\/uploads\/2021\/12\/kreisel-k05-1.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-826e46df-2ffa-4eb8-a599-964382345e79\">Herunterladen<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um diese Aufgabe zu l\u00f6sen, bedienen wir uns einer Mischung aus Kinematik, Relativkinematik und nat\u00fcrlich Schwerpunkt- und Drehimpulssatz. Zuerst muss bestimmt werden wie gro\u00df f\u00fcr gegebenes vp die Winkelgeschwindigkeit \u03c9 wird. Dann k\u00f6nnen wir uns \u00fcberlegen welche absolute Beschleunigung der Schwerpunkt des M\u00fchlsteins S aufweist. Aus dieser absoluten Beschleunigung l\u00e4sst sich dann der Schwerpunktsatz anschreiben und die Kr\u00e4fte berechnen. Zum Schluss bestimmen wir noch den Drehimpuls f\u00fcr den M\u00fchlstein und berechnen aus diesem die Momente. Wie das im Detail funktioniert erkl\u00e4re ich im angeh\u00e4ngten YouTube Video.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"712\" height=\"401\" src=\"https:\/\/www.youtube.com\/embed\/Pdc4zSf6mNo?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn ihr Fragen habt schreibt bitte hier oder auf YouTube einen Kommentar. Ich werde eure Fragen schnellstm\u00f6glich beantworten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hat euch das Video gefallen? Dann lasst bitte ein Like auf YouTube da. Abonniert auch unbedingt den Kanal um kein Video zu verpassen. Ihr helft mir damit enorm. Vielen Dank!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bis n\u00e4chste Woche mit einem weiteren Beispiel,<br>Markus <\/p>","protected":false},"excerpt":{"rendered":"<p>Herzlich Willkommen! Heute wollen wir uns ein Beispiel aus dem Bereich Kreiseldynamik ansehen, und zwar folgende M\u00fchle: Die dargestellte M\u00fchle wird mit der Winkelgeschwindigkeit&nbsp;\u03a9=const.&nbsp;angetrieben. Der M\u00fchlstein habe seinen Schwerpunkt in&nbsp;S, seine Masse sei&nbsp;m&nbsp;und seine Massentr\u00e4gheitsmomente&nbsp;I1&nbsp;sowie&nbsp;I2=I3. Ges.:*die erforderliche Winkelgeschwindigkeit&nbsp;\u03c9=const., sodass der M\u00fchlstein im Punkt&nbsp;P&nbsp;mit der Geschwindigkeit&nbsp;-vp e2&nbsp;gleitet.*die Beschleunigung des Punktes&nbsp;P.*die Winkelgeschwindigkeit des M\u00fchlsteins im&nbsp;e_1-e_2-e_3&nbsp;Koordinatensystem.*die resultierende Einzelkraft &hellip; <a href=\"https:\/\/technischemechanik.com\/en\/2021\/12\/02\/dynamik-kreisel-muhlstein\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Kreiseldynamik: M\u00fchlstein<\/span><\/a><\/p>","protected":false},"author":110396568,"featured_media":346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2602546,1145536,5004009],"tags":[129538,25466,2245662,7978,13261836,102130347,1641709,12237,750913297,35890,166867,3480,807373,40987001,2517859,750913303,947685,32590,5685069,727263877,662707,7091101,215605283,2870029,720191,10126,73726871,161115,172005,2411,122145655,14084,1121513,727213064,727213067,727213062,1097356,2722,33601,17744,21321],"class_list":["post-213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubungsaufgaben","category-dynamik","category-kreisel","tag-aufgabe","tag-beispiel","tag-beschleunigung","tag-bildung","tag-digitale-bildung","tag-digitaler-unterricht","tag-digitalisierung","tag-dynamics","tag-dynamik","tag-featured","tag-hochschule","tag-homeschooling","tag-ingenieur","tag-ingenieurwissenschaft","tag-krafte","tag-kreisel","tag-losung","tag-lehre","tag-lernhilfe","tag-markus-orthaber","tag-maschinenbau","tag-maschinenbauingenieur","tag-mathematik-lernen","tag-muhle","tag-mechanik","tag-physik","tag-physik-nachhilfe","tag-screencast","tag-studieren","tag-studium","tag-studyhelp","tag-technik","tag-technische-mechanik","tag-technische-mechanik-1","tag-technische-mechanik-2-2","tag-technische-mechanik-2","tag-tm1","tag-uni","tag-universitat","tag-wissen","tag-wissenschaft"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/technischemechanik.com\/wp-content\/uploads\/2021\/12\/kreisel-wordpress.png?fit=512%2C512&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7UJuu-3r","jetpack-related-posts":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/posts\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/users\/110396568"}],"replies":[{"embeddable":true,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":16,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"predecessor-version":[{"id":361,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/posts\/213\/revisions\/361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/media\/346"}],"wp:attachment":[{"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/technischemechanik.com\/en\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}